{"id":37918,"date":"2025-11-24T12:47:20","date_gmt":"2025-11-24T15:47:20","guid":{"rendered":"https:\/\/unicopas.org.br\/noticias\/?p=37918"},"modified":"2025-11-24T12:47:21","modified_gmt":"2025-11-24T15:47:21","slug":"mds-lanca-marco-de-sistemas-alimentares-e-clima-para-as-politicas-publicas","status":"publish","type":"post","link":"https:\/\/unicopas.org.br\/noticias\/mds-lanca-marco-de-sistemas-alimentares-e-clima-para-as-politicas-publicas\/","title":{"rendered":"MDS lan\u00e7a Marco de Sistemas Alimentares e Clima para as Pol\u00edticas P\u00fablicas"},"content":{"rendered":"\n<p><strong>Documento busca coer\u00eancia e coordena\u00e7\u00e3o entre os setores para garantir uma transi\u00e7\u00e3o justa para sistemas alimentares sustent\u00e1veis e equitativos<\/strong><\/p>\n\n\n\n<p>O Minist\u00e9rio do Desenvolvimento e Assist\u00eancia Social, Fam\u00edlia e Combate \u00e0 Fome (MDS) lan\u00e7ou, durante a COP30, uma nova diretriz para orientar as pol\u00edticas p\u00fablicas que ligam a produ\u00e7\u00e3o de alimentos \u00e0s mudan\u00e7as clim\u00e1ticas. O documento, chamado Marco de Sistemas Alimentares e Clima para Pol\u00edticas P\u00fablicas, busca alinhar as a\u00e7\u00f5es dos governos federal, estaduais e municipais nessa agenda.<br><br>Na cerim\u00f4nia, o titular do MDS, Wellington Dias, defendeu que a luta contra a fome deve ser trabalhada de forma integrada \u00e0 luta contra a pobreza e ao enfrentamento \u00e0 emerg\u00eancia clim\u00e1tica. \u201cQuem mais sente o impacto do clima s\u00e3o aqueles em situa\u00e7\u00e3o de vulnerabilidade. Para isso, \u00e9 necess\u00e1ria a\u00e7\u00e3o conjunta, \u00a0com coer\u00eancia e urg\u00eancia entre as pol\u00edticas p\u00fablicas\u201d, apontou.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>&#8220;Quem mais sente o impacto do clima s\u00e3o aqueles em situa\u00e7\u00e3o de vulnerabilidade&#8221;<\/p>\n\n\n\n<p><em>Wellington Dias, ministro&nbsp;do Desenvolvimento e Assist\u00eancia Social, Fam\u00edlia e Combate \u00e0 Fome<\/em><\/p>\n<\/blockquote>\n\n\n\n<p>Um dos objetivos do Marco \u00e9 considerar os impactos que o sistema alimentar gera no meio ambiente, como o uso da \u00e1gua no cultivo, por exemplo. \u201cO Marco serve base para qualquer pa\u00eds do mundo. Foi constru\u00eddo em conjunto entre governos e sociedade e prop\u00f5e meios e estrat\u00e9gia para regenerar, adaptar e transformar esses sistemas frente aos desafios clim\u00e1ticos, atuais e futuros\u201d, explicou Wellington Dias.&nbsp;<br><br>O documento apresenta como princ\u00edpios o Direito Humano \u00e0 Alimenta\u00e7\u00e3o Adequada, al\u00e9m da soberania alimentar, justi\u00e7a clim\u00e1tica, sustentabilidade em todas as dimens\u00f5es, abordagem sist\u00eamica e o trabalho conjunto entre governos centrais e locais, integrado com a sociedade.<\/p>\n\n\n\n<p>Em seu discurso, o ministro lembrou da&nbsp;<a href=\"https:\/\/www.gov.br\/mds\/pt-br\/noticias-e-conteudos\/desenvolvimento-social\/noticias-desenvolvimento-social\/cop30-agricultores-familiares-no-para-garantem-sustento-com-producao-sustentavel-e-recuperacao-ambiental\">visita feita a um assentamento de agricultores<\/a>&nbsp;familiares na regi\u00e3o metropolitana de Bel\u00e9m. L\u00e1, ele viu o cultivo de m\u00faltiplos alimentos regionais, como a\u00e7a\u00ed e cupua\u00e7u, em meio \u00e0 floresta, sem degrada\u00e7\u00e3o, o que tem contribu\u00eddo para regenera\u00e7\u00e3o de igarap\u00e9s que haviam sido prejudicados por monocultura.<\/p>\n\n\n\n<p>\u201cA agenda que propomos inclui o fortalecimento da agroecologia, da agricultura familiar, a promo\u00e7\u00e3o de alimenta\u00e7\u00e3o saud\u00e1vel, o reconhecimento dos saberes ancestrais dos povos e comunidades tradicionais, a promo\u00e7\u00e3o de cadeias da sociobiodiversidade, a amplia\u00e7\u00e3o do acesso \u00e0 \u00e1gua e a redu\u00e7\u00e3o de perdas e desperd\u00edcio de movimentos\u201d, explicou. \u201cTamb\u00e9m buscamos dar visibilidade \u00e0s experi\u00eancias locais e promover o di\u00e1logo entre diferentes atores\u201d, acrescentou.<br><br>Dias tamb\u00e9m salientou a uni\u00e3o de esfor\u00e7os. \u201cConvidamos todos os pa\u00edses, organiza\u00e7\u00f5es e lideran\u00e7as a se somarem a esse esfor\u00e7o. Juntos podemos construir sistemas alimentares mais resilientes, saud\u00e1veis e sustent\u00e1veis para garantir um futuro digno para todos e todas\u201d, finalizou.&nbsp;<\/p>\n\n\n\n<p>Confira&nbsp;<a href=\"https:\/\/www.gov.br\/mds\/pt-br\/acoes-e-programas\/promocao-da-alimentacao-adequada-e-saudavel\/marco-de-referencia-sobre-sistemas-alimentares-e-clima-para-politicas-publicas\">aqui<\/a>&nbsp;o&nbsp;Marco de Sistemas Alimentares e Clima para Pol\u00edticas P\u00fablicas<\/p>\n\n\n\n<p><strong>Direito Humano \u00e0 Alimenta\u00e7\u00e3o Adequada<\/strong><\/p>\n\n\n\n<p>Para a secret\u00e1ria Nacional de Seguran\u00e7a Alimentar e Nutricional do MDS, Lilian Rahal, a iniciativa est\u00e1 alinhada ao compromisso do MDS com o Direito Humano \u00e0 Alimenta\u00e7\u00e3o Adequada. &nbsp;\u201cMais do que um documento, o Marco \u00e9 um convite \u00e0 a\u00e7\u00e3o, e um compromisso pol\u00edtico e institucional do Estado brasileiro. \u00c9 um convite para que possamos juntos refletir, buscar realidades, mobilizar atores e implementar a\u00e7\u00f5es, considerando as realidades dos territ\u00f3rios\u201d, explicou.<\/p>\n\n\n\n<p>Al\u00e9m disso, Rahal pontuou que, desde 2023, o MDS implementa um redesenho das pol\u00edticas, que inclui o Programa Cisternas, a Estrat\u00e9gia Alimenta Cidades presente 102 cidades e o investimento em agricultura urbana.<br><br><strong>Desafio<\/strong><\/p>\n\n\n\n<p>Embora o Brasil tenha alcan\u00e7ado a sa\u00edda do Mapa da Fome, conforme an\u00fancio da ONU em julho de 2025, a crise do clima apresenta um novo desafio \u00e0 seguran\u00e7a alimentar. A maneira com os alimentos s\u00e3o produzidos, distribu\u00eddos e consumidos afetam a crise clim\u00e1tica e, ao mesmo tempo, o clima desregulado atinge diretamente a capacidade dos sistemas alimentares de se manterem. Isso, prejudica especialmente principalmente para grupos vulner\u00e1veis, como as popula\u00e7\u00f5es mais pobres.<br><br><strong>Caminhos para uma transi\u00e7\u00e3o justa<\/strong><\/p>\n\n\n\n<p>As premissas do Marco foram constru\u00eddas com base em evid\u00eancias cient\u00edficas consolidadas, que demonstram que a mudan\u00e7a do clima \u00e9 uma realidade j\u00e1 percept\u00edvel, que os sistemas alimentares s\u00e3o tanto causa quanto consequ\u00eancia dessa crise, e que seus efeitos agravam desigualdades e vulnerabilidades. A partir dessa compreens\u00e3o, o documento prop\u00f5e caminhos priorit\u00e1rios para a transforma\u00e7\u00e3o.<\/p>\n\n\n\n<p>Entre os caminhos apontados est\u00e3o: reorientar os modos de produ\u00e7\u00e3o com foco na transi\u00e7\u00e3o agroecol\u00f3gica; fortalecer a agricultura familiar e a economia solid\u00e1ria; garantir seguran\u00e7a h\u00eddrica para produ\u00e7\u00e3o e consumo; valorizar a sociobiodiversidade; conceber o abastecimento alimentar como pol\u00edtica de Estado; estimular cidades resilientes; promover ambientes que favore\u00e7am pr\u00e1ticas alimentares saud\u00e1veis; reduzir perdas e desperd\u00edcio de alimentos; e investir em ci\u00eancia, tecnologia e inova\u00e7\u00e3o para sistemas alimentares sustent\u00e1veis.<\/p>\n\n\n\n<p>Participaram do lan\u00e7amento do Marco, o secret\u00e1rio Nacional de Mudan\u00e7a do Clima \u00a0do Minist\u00e9rio do Meio Ambiente e Mudan\u00e7as Clim\u00e1ticas, Aloisio Lopes Pereira de Melo; a presidente do Conselho Nacional de Seguran\u00e7a Alimentar e Nutricional (Consea), Elisabetta Recine; representante do Instituto Clima e Sociedade, Maria Netto e o coordenador-executivo da Articula\u00e7\u00e3o Nacional de Agroecologia (ANA), Paulo Petersen.<br><br>Fonte: Assessoria de Comunica\u00e7\u00e3o &#8211; MDS\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Documento busca coer\u00eancia e coordena\u00e7\u00e3o entre os setores para garantir uma transi\u00e7\u00e3o justa para sistemas alimentares sustent\u00e1veis e equitativos O Minist\u00e9rio do Desenvolvimento e Assist\u00eancia <a class=\"mh-excerpt-more\" href=\"https:\/\/unicopas.org.br\/noticias\/mds-lanca-marco-de-sistemas-alimentares-e-clima-para-as-politicas-publicas\/\" title=\"MDS lan\u00e7a Marco de Sistemas Alimentares e Clima para as Pol\u00edticas P\u00fablicas\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":5,"featured_media":37919,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-37918","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/unicopas.org.br\/noticias\/wp-json\/wp\/v2\/posts\/37918","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/unicopas.org.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/unicopas.org.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/unicopas.org.br\/noticias\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/unicopas.org.br\/noticias\/wp-json\/wp\/v2\/comments?post=37918"}],"version-history":[{"count":1,"href":"https:\/\/unicopas.org.br\/noticias\/wp-json\/wp\/v2\/posts\/37918\/revisions"}],"predecessor-version":[{"id":37920,"href":"https:\/\/unicopas.org.br\/noticias\/wp-json\/wp\/v2\/posts\/37918\/revisions\/37920"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/unicopas.org.br\/noticias\/wp-json\/wp\/v2\/media\/37919"}],"wp:attachment":[{"href":"https:\/\/unicopas.org.br\/noticias\/wp-json\/wp\/v2\/media?parent=37918"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/unicopas.org.br\/noticias\/wp-json\/wp\/v2\/categories?post=37918"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/unicopas.org.br\/noticias\/wp-json\/wp\/v2\/tags?post=37918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}