{"id":35649,"date":"2022-02-01T16:53:14","date_gmt":"2022-02-01T19:53:14","guid":{"rendered":"https:\/\/unicopas.org.br\/?p=35649"},"modified":"2022-03-03T22:49:48","modified_gmt":"2022-03-04T01:49:48","slug":"enquanto-agirmos-sozinhos-seremos-apenas-uma-abelha","status":"publish","type":"post","link":"https:\/\/unicopas.org.br\/noticias\/enquanto-agirmos-sozinhos-seremos-apenas-uma-abelha\/","title":{"rendered":"\u201cEnquanto agirmos sozinhos seremos apenas uma abelha\u201d"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\"><em>Aula magna deu in\u00edcio a mais uma curso online promovido pela Unicopas com o apoio da Uni\u00e3o Europeia; mais de 130 pessoas iniciaram capacita\u00e7\u00e3o em Economia Solid\u00e1ria como Estrat\u00e9gia de Desenvolvimento&nbsp;<\/em><\/h4>\n\n\n\n<p>\u201cN\u00f3s temos condi\u00e7\u00f5es de sermos protagonistas de uma economia diferente, mas enquanto agirmos sozinhos seremos apenas uma abelha. Quando agirmos como um enxame, n\u00f3s seremos protagonistas da mudan\u00e7a\u201d. Foi com essas palavras que Francisco Dal Chiavon, presidente da Unicopas (Uni\u00e3o Nacional das Organiza\u00e7\u00f5es Cooperativistas Solid\u00e1rias) deu as boas-vindas aos mais de 130 inscritas e inscritos para o curso \u2018Economia Solid\u00e1ria como Estrat\u00e9gia de Desenvolvimento\u2019, promovido pela entidade com o apoio da Uni\u00e3o Europeia.&nbsp;<\/p>\n\n\n\n<p>A capacita\u00e7\u00e3o teve in\u00edcio no \u00faltimo final de semana com o objetivo de ampliar o acesso \u00e0s experi\u00eancias e informa\u00e7\u00f5es sobre economia solid\u00e1ria, bem como contribuir para a organiza\u00e7\u00e3o de empreendimentos econ\u00f4micos solid\u00e1rios no Brasil.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Perfil das\/os participantes<\/strong><\/h4>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"720\" src=\"https:\/\/unicopas.org.br\/corporativo\/wp-content\/uploads\/2022\/02\/curso-unicopas-economia-solidaria-1152x720.jpeg\" alt=\"\" class=\"wp-image-35652\" srcset=\"https:\/\/unicopas.org.br\/noticias\/wp-content\/uploads\/sites\/2\/2022\/02\/curso-unicopas-economia-solidaria-1152x720.jpeg 1152w, https:\/\/unicopas.org.br\/noticias\/wp-content\/uploads\/sites\/2\/2022\/02\/curso-unicopas-economia-solidaria-821x513.jpeg 821w, https:\/\/unicopas.org.br\/noticias\/wp-content\/uploads\/sites\/2\/2022\/02\/curso-unicopas-economia-solidaria-768x480.jpeg 768w, https:\/\/unicopas.org.br\/noticias\/wp-content\/uploads\/sites\/2\/2022\/02\/curso-unicopas-economia-solidaria.jpeg 1280w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><\/figure>\n\n\n\n<p>Com representantes de todas as centrais afiliadas \u00e0 Unicopas &#8211; Unicafes Nacional, Unisol Brasil, Concrab e Unicatadores -, o curso conta com a participa\u00e7\u00e3o de pessoas de todas as regi\u00f5es do Brasil, com destaque para o Nordeste.&nbsp;<\/p>\n\n\n\n<p>Grande parte vem da rede p\u00fablica de ensino e possui superior completo. As mulheres s\u00e3o a maioria e quase 70% das inscri\u00e7\u00f5es foram de pessoas que se declararam pretas ou pardas. A capacita\u00e7\u00e3o chamou mais a aten\u00e7\u00e3o de quem est\u00e1 na faixa et\u00e1ria de 30 a 59 anos.&nbsp;<\/p>\n\n\n\n<p>\u201cFortalecer a unidade do cooperativismo solid\u00e1rio. \u00c9 isso que estamos construindo aqui. Somente a unidade na diversidade ser\u00e1 capaz de apresentar uma proposta eficaz para a transforma\u00e7\u00e3o social\u201d, destacou Leonardo Pinho, dirigente da Unicopas e presidente da Unisol Brasil.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Metodologia<\/strong><\/h4>\n\n\n\n<p>Pensada para lideran\u00e7as do cooperativismo solid\u00e1rio, toda a metodologia do curso foi constru\u00edda coletivamente pelo N\u00facleo Pedag\u00f3gico da Unicopas. Selma Santos destacou que durante toda a capacita\u00e7\u00e3o ser\u00e3o abordados aspectos e desafios da realidade pol\u00edtica e econ\u00f4mica brasileira vinculadas com a realidade local. \u201cVamos tratar de um desenvolvimento consciente a partir da integralidade humana\u201d.&nbsp;<\/p>\n\n\n\n<p>Fazem parte do N\u00facleo Pedag\u00f3gico da Unicopas, al\u00e9m de Selma, Kelly Santiago, Jorge Silva e Alex Cardoso. O processo metodol\u00f3gico tamb\u00e9m contou com o apoio de Daniel Pereira e Marislene Nogueira, integrantes da centrais afiliadas \u00e0 Unicopas, e dos assessores pol\u00edticos da organiza\u00e7\u00e3o Eugenio Alves, Daniel Rech, Qu\u00eaner Chaves e Adilson Guimieiro.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Somos enxame&nbsp;&nbsp;<\/strong><\/h4>\n\n\n\n<p class=\"has-text-align-left\">Inspiradas e inspirados pela poesia \u2018Seguimos juntos\u2019 de Ren\u00ea Esteban, o curso online \u2018Economia Solid\u00e1ria como Estrat\u00e9gia de Desenvolvimento\u2019 segue at\u00e9 abril deste ano.&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>Seguimos Juntos<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center\"><em>N\u00e3o somos e representamos apenas um,<\/em><br><em>N\u00e3o somos e representamos apenas poucos ou muitos.<\/em><br><em>Mais que isso, somos e representamos a maioria! Se n\u00e3o, todos!<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center\"><em>Somos e representamos todos os 14 milh\u00f5es de desempregados que acordam sem saber se v\u00e3o ter o que comer, que hoje est\u00e3o sem perspectiva de vida!<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center\"><em>Somos e representamos todos os mais de 600 mil mortos pela pandemia, que pereceram nas garras de um governo da morte!<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center\"><em>Somos e representamos todos os \u00f3rf\u00e3os dessas fam\u00edlias destro\u00e7adas, somos e representamos os trabalhadores da sa\u00fade, e tamb\u00e9m todos aqueles que foram e ainda s\u00e3o desrespeitados por uma necessidade de mercado que s\u00f3 fez matar, envenenar e concentrar!<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center\"><em>Somos e representamos todos os que t\u00eam fome de oportunidade, de respeito, de equidade, de soberania, de poder sonhar em ser mais&#8230; porque a fome, n\u00e3o se d\u00e1 apenas pela falta de comida no prato! A fome de \u201cser\u201d tamb\u00e9m nos assola!!<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center\"><em>Somos e representamos todos aqueles miser\u00e1veis na vida, contra todos \u00e0queles malditos engravatados e conglomerados de capitais que comandam, do alto dos arranha-c\u00e9us, as c\u00fapulas de decis\u00e3o do capitalismo e que definem, inclusive, o que tem de ser meio- ambiente, o que tem de ser fome e o que tem de ser participa\u00e7\u00e3o pol\u00edtica do povo! S\u00e3o contra esses que lutamos pois, sem escr\u00fapulos, s\u00e3o esses que fazem a mis\u00e9ria de toda esp\u00e9cie renascer e agravar entre n\u00f3s!<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center\"><em>Mas s\u00f3 podemos ser e representar, se estivermos unidos, juntos, rumando para um mesmo destino; alinhados, cerrando fileiras para um mundo que seja bom para a maioria! E s\u00f3 se estivermos unidos que poderemos venc\u00ea-los! Pois como diria Marx, \u201cuma ideia torna-se uma for\u00e7a material quando ganha as massas organizadas\u201d.<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center\"><em>Ent\u00e3o, sigamos! Sigamos firmes na luta, sigamos desafiando em favor da inclus\u00e3o e contra as mazelas causadas por essa cultura do \u201cter\u201d e n\u00e3o do \u201cser\u201d que nos cerca! Mas sem desiludir, e com muita for\u00e7a e tenacidade, pois, s\u00f3 assim, passaremos a viver no outro, passaremos a ser tamb\u00e9m uma ideia que n\u00e3o se desfaz nunca, pois geraremos palavras que, como sementes, se espalhar\u00e3o com o vento!<\/em><\/p>\n\n\n\n<p class=\"has-text-align-right\"><em>Ren\u00ea Esteban<\/em><br><em>11\/2021<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Aula magna deu in\u00edcio a mais uma curso online promovido pela Unicopas com o apoio da Uni\u00e3o Europeia; mais de 130 pessoas iniciaram capacita\u00e7\u00e3o em Economia Solid\u00e1ria como Estrat\u00e9gia de Desenvolvimento <\/p>\n<\/div>","protected":false},"author":5,"featured_media":34293,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","footnotes":""},"categories":[491],"tags":[65,67,470,475,75,103,106],"class_list":["post-35649","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unicopas","tag-cooperativismo","tag-cooperativismo-solidario","tag-curso","tag-curso-online","tag-economia-solidaria","tag-uniao-europeia","tag-unicopas"],"_links":{"self":[{"href":"https:\/\/unicopas.org.br\/noticias\/wp-json\/wp\/v2\/posts\/35649","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/unicopas.org.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/unicopas.org.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/unicopas.org.br\/noticias\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/unicopas.org.br\/noticias\/wp-json\/wp\/v2\/comments?post=35649"}],"version-history":[{"count":1,"href":"https:\/\/unicopas.org.br\/noticias\/wp-json\/wp\/v2\/posts\/35649\/revisions"}],"predecessor-version":[{"id":35838,"href":"https:\/\/unicopas.org.br\/noticias\/wp-json\/wp\/v2\/posts\/35649\/revisions\/35838"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/unicopas.org.br\/noticias\/wp-json\/wp\/v2\/media\/34293"}],"wp:attachment":[{"href":"https:\/\/unicopas.org.br\/noticias\/wp-json\/wp\/v2\/media?parent=35649"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/unicopas.org.br\/noticias\/wp-json\/wp\/v2\/categories?post=35649"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/unicopas.org.br\/noticias\/wp-json\/wp\/v2\/tags?post=35649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}